{"id":348768,"date":"2022-09-16T18:39:03","date_gmt":"2022-09-16T09:39:03","guid":{"rendered":"https:\/\/www.deviser.co.jp\/products\/mc-premium-skr-skr-wh-mh-15458"},"modified":"2024-02-19T16:45:33","modified_gmt":"2024-02-19T07:45:33","slug":"mc-premium-skr-skr-wh-mh-15458","status":"publish","type":"products","link":"https:\/\/www.deviser.co.jp\/en\/products\/mc-premium-skr-skr-wh-mh-15458","title":{"rendered":"MC-Premium\/SKR SKR-WH-MH #15458"},"content":{"rendered":"\n\t\n\t\t\t<div class=\"c-grid c-grid_loose\">\n\t\t\t\t<div class=\"c-grid__u c-grid__u_medium_1of2 p-product__hascolor\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"p-color-list p-color-list_large\">\n\t\t\t\t\t\t\t\t\t<div class=\"p-color-list__img\"><img width=\"1000\" height=\"327\" src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP.png 1000w, https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP-450x147.png 450w, https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP-800x262.png 800w, https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP-768x251.png 768w, https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP-600x196.png 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"c-grid__u c-grid__u_medium_1of2\">\n\n\t\t\t\t\t<h2 class=\"p-product__heading\">COLOR<\/h2>\n\t\t\t\t\t<div class=\"p-color-list\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"p-color-list__item\">\n\t\t\t\t\t\t\t\t\t<div class=\"p-color-list__img test\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"venobox\" data-gall=\"color\" href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP.png\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"327\" src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP.png 1000w, https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP-450x147.png 450w, https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP-800x262.png 800w, https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP-768x251.png 768w, https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/14585-TOP-600x196.png 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<p class=\"p-color-list__name\">SKR-WH-MH\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\n\t\n\n\n\n<div class=\"wp-block-group c-row p-spec\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-egb-c-grid c-grid\">\n<div class=\"wp-block-egb-c-grid-unit c-grid__u c-grid__u_medium_1of2\">\n\n\t<div class=\"p-gallery\">\n\t\t<div class=\"p-gallery__main\">\n\t\t\t<div class=\"swiper-container\" id=\"js-gallery\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-5RR.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-5RR.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-9.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-9.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-13.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-13.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-6.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-6.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-7.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-7.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-8.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-8.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-10.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-10.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-11.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-11.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-12.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-12.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-14.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-14.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-1.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-1.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-2.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-2.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-3.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-3.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-4.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-4.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<!-- Add Arrows -->\n\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"p-gallery__thumbs swiper-container\" id=\"js-thumbs\">\n\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-5RR.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-9.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-13.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-6.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-7.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-8.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-10.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-11.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-12.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-14.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-1.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-2.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-3.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2022\/09\/15485-0011-4.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-egb-c-grid-unit c-grid__u c-grid__u_medium_1of2\">\n<h2 class=\"p-spec__title\">Specification<\/h2>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Body Top<\/dt><dd class=\"c-dl__dd\">\n<p>Sakura<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Body<\/dt><dd class=\"c-dl__dd\">\n<p>Ash<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Neck<\/dt><dd class=\"c-dl__dd\">\n<p>Maple<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Fingerboard<\/dt><dd class=\"c-dl__dd\">\n<p>Ebony<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Nut<\/dt><dd class=\"c-dl__dd\">\n<p>Oiled Bone<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Bridge<\/dt><dd class=\"c-dl__dd\">\n<p>GOTOH\u00aeGE108TS<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Machineheads<\/dt><dd class=\"c-dl__dd\">\n<p>GOTOH\u00aeSD91-05M MG<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Fret<\/dt><dd class=\"c-dl__dd\">\n<p>Jescar\u00ae Evolition Gold9662NS<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Pickups<\/dt><dd class=\"c-dl__dd\">\n<p>Momose VS1<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Controls<\/dt><dd class=\"c-dl__dd\">\n<p>1Vol,2Tone, 5way PU Selector<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Scale<\/dt><dd class=\"c-dl__dd\">\n<p>25.5inch<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Fingerboard Radius<\/dt><dd class=\"c-dl__dd\">\n<p>210R<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Finish<\/dt><dd class=\"c-dl__dd\">\n<p>Top Lacquer<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Strings<\/dt><dd class=\"c-dl__dd\">\n<p>Elixir NANOWEB Light(.010-.046)<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Accessories<\/dt><dd class=\"c-dl__dd\">\n<p>Protective Case, Allen Wrench, COA<\/p>\n<\/dd><\/dl>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-group is-style-medium\"><div class=\"wp-block-group__inner-container\"><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container\"><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":205002,"menu_order":3312,"template":"","meta":{"spay_email":"","_links_to":"","_links_to_target":""},"brand-cat":[1031,1030,1209],"products-cat":[819],"model-cat":[829],"shape-cat":[917],"price-cat":[831],"products-person-cat":[],"products-year-cat":[],"products-feature-cat":[966,1231,1369],"products-release-cat":[974,1211],"_links":{"self":[{"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products\/348768"}],"collection":[{"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/types\/products"}],"author":[{"embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":0,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products\/348768\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/media\/205002"}],"wp:attachment":[{"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/media?parent=348768"}],"wp:term":[{"taxonomy":"brand-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/brand-cat?post=348768"},{"taxonomy":"products-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-cat?post=348768"},{"taxonomy":"model-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/model-cat?post=348768"},{"taxonomy":"shape-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/shape-cat?post=348768"},{"taxonomy":"price-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/price-cat?post=348768"},{"taxonomy":"products-person-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-person-cat?post=348768"},{"taxonomy":"products-year-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-year-cat?post=348768"},{"taxonomy":"products-feature-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-feature-cat?post=348768"},{"taxonomy":"products-release-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-release-cat?post=348768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}