{"id":67289,"date":"2021-04-08T15:53:32","date_gmt":"2021-04-08T06:53:32","guid":{"rendered":"https:\/\/www.deviser.co.jp\/?post_type=products&#038;p=67289"},"modified":"2022-12-09T17:14:42","modified_gmt":"2022-12-09T08:14:42","slug":"hom-yozakura19-summer-das-atb","status":"publish","type":"products","link":"https:\/\/www.deviser.co.jp\/en\/products\/hom-yozakura19-summer-das-atb","title":{"rendered":"HOM-Yozakura&#8217;19 Summer D,A,S\/ATB"},"content":{"rendered":"\n\t\n\t\t\t<div class=\"c-grid c-grid_loose\">\n\t\t\t\t<div class=\"c-grid__u c-grid__u_medium_1of2 p-product__hascolor\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"p-color-list p-color-list_large\">\n\t\t\t\t\t\t\t\t\t<div class=\"p-color-list__img\"><img width=\"1000\" height=\"388\" src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/HOM-Yozakura-19-Summer-D-A-S-ATB.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/HOM-Yozakura-19-Summer-D-A-S-ATB.png 1000w, https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/HOM-Yozakura-19-Summer-D-A-S-ATB-600x233.png 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"c-grid__u c-grid__u_medium_1of2\">\n\n\t\t\t\t\t<h2 class=\"p-product__heading\">COLOR<\/h2>\n\t\t\t\t\t<div class=\"p-color-list\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"p-color-list__item\">\n\t\t\t\t\t\t\t\t\t<div class=\"p-color-list__img test\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"venobox\" data-gall=\"color\" href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/HOM-Yozakura-19-Summer-D-A-S-ATB.png\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"388\" src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/HOM-Yozakura-19-Summer-D-A-S-ATB.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/HOM-Yozakura-19-Summer-D-A-S-ATB.png 1000w, https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/HOM-Yozakura-19-Summer-D-A-S-ATB-600x233.png 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<p class=\"p-color-list__name\">YZBL\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"p-color-list__jan\">Jan \/ <br class=\"u-hidden-medium\">4571470378686<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\n\t\n\n\n\n<div class=\"wp-block-group c-row p-spec\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-egb-c-grid c-grid\">\n<div class=\"wp-block-egb-c-grid-unit c-grid__u c-grid__u_medium_1of2\">\n\n\t<div class=\"p-gallery\">\n\t\t<div class=\"p-gallery__main\">\n\t\t\t<div class=\"swiper-container\" id=\"js-gallery\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-001_0.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-001_0.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-002_0.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-002_0.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-003_0.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-003_0.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-004_0.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-004_0.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-005_0.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-005_0.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-007_0.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-007_0.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-009_0.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-009_0.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-008_0.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-008_0.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-010_0.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-010_0.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-011_0.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-011_0.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-012_0.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-012_0.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-013_0.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-013_0.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/1907-hdyoz07-3.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/1907-hdyoz07-3.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/1907-hdyoz08-3.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/1907-hdyoz08-3.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<!-- Add Arrows -->\n\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"p-gallery__thumbs swiper-container\" id=\"js-thumbs\">\n\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-001_0.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-002_0.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-003_0.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-004_0.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-005_0.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-007_0.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-009_0.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-008_0.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-010_0.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-011_0.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-012_0.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/20190729-013_0.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/1907-hdyoz07-3.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2020\/12\/1907-hdyoz08-3.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-egb-c-grid-unit c-grid__u c-grid__u_medium_1of2\">\n<h2 class=\"p-spec__title\">Specification<\/h2>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Body Top<\/dt><dd class=\"c-dl__dd\">\n<p>Sitka Spruce<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Body Side&amp;Back<\/dt><dd class=\"c-dl__dd\">\n<p>Yamazakura<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Neck<\/dt><dd class=\"c-dl__dd\">\n<p>African Mahogany <\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Fingerboard<\/dt><dd class=\"c-dl__dd\">\n<p>Ebony<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Nut<\/dt><dd class=\"c-dl__dd\">\n<p>High Density Bone(Water buffalo bone)<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Saddle<\/dt><dd class=\"c-dl__dd\">\n<p>High Density Bone(Water buffalo bone)<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Bridge<\/dt><dd class=\"c-dl__dd\">\n<p>Ebony<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Machineheads<\/dt><dd class=\"c-dl__dd\">\n<p>GOTOH\/SG301 01C<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Fret<\/dt><dd class=\"c-dl__dd\">\n<p>HHF-AG<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Scale<\/dt><dd class=\"c-dl__dd\">\n<p>645mm<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Width at nut<\/dt><dd class=\"c-dl__dd\">\n<p>43.0mm<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Fingerboard Radius<\/dt><dd class=\"c-dl__dd\">\n<p>400R<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Bracing<\/dt><dd class=\"c-dl__dd\">\n<p>Scalloped Advanced Rear Shift X Bracing<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Finish<\/dt><dd class=\"c-dl__dd\">\n<p>Thin Urethane<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Accessories<\/dt><dd class=\"c-dl__dd\">\n<p>Hard Case, Allen Wrench, COA<\/p>\n<\/dd><\/dl>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":67333,"menu_order":5176,"template":"","meta":{"spay_email":"","_links_to":"","_links_to_target":""},"brand-cat":[827],"products-cat":[828],"model-cat":[829,884],"shape-cat":[909],"price-cat":[831],"products-person-cat":[],"products-year-cat":[],"products-feature-cat":[966,972,1232,1276],"products-release-cat":[974,1211],"_links":{"self":[{"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products\/67289"}],"collection":[{"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/types\/products"}],"author":[{"embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products\/67289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/media\/67333"}],"wp:attachment":[{"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/media?parent=67289"}],"wp:term":[{"taxonomy":"brand-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/brand-cat?post=67289"},{"taxonomy":"products-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-cat?post=67289"},{"taxonomy":"model-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/model-cat?post=67289"},{"taxonomy":"shape-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/shape-cat?post=67289"},{"taxonomy":"price-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/price-cat?post=67289"},{"taxonomy":"products-person-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-person-cat?post=67289"},{"taxonomy":"products-year-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-year-cat?post=67289"},{"taxonomy":"products-feature-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-feature-cat?post=67289"},{"taxonomy":"products-release-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-release-cat?post=67289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}