{"id":69772,"date":"2021-04-13T13:32:21","date_gmt":"2021-04-13T04:32:21","guid":{"rendered":"https:\/\/www.deviser.co.jp\/?post_type=products&#038;p=69772"},"modified":"2023-06-22T17:48:10","modified_gmt":"2023-06-22T08:48:10","slug":"mjm-fuyuzakura-se19w","status":"publish","type":"products","link":"https:\/\/www.deviser.co.jp\/en\/products\/mjm-fuyuzakura-se19w","title":{"rendered":"MJM-FUYUZAKURA-SE&#8217;19W"},"content":{"rendered":"\n\t\n\t\t\t<div class=\"c-grid c-grid_loose\">\n\t\t\t\t<div class=\"c-grid__u c-grid__u_medium_1of2 p-product__hascolor\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"p-color-list p-color-list_large\">\n\t\t\t\t\t\t\t\t\t<div class=\"p-color-list__img\"><img width=\"1000\" height=\"338\" src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/MJM-FUYUZAKURA-SE19W.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/MJM-FUYUZAKURA-SE19W.png 1000w, https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/MJM-FUYUZAKURA-SE19W-600x203.png 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"c-grid__u c-grid__u_medium_1of2\">\n\n\t\t\t\t\t<h2 class=\"p-product__heading\">COLOR<\/h2>\n\t\t\t\t\t<div class=\"p-color-list\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"p-color-list__item\">\n\t\t\t\t\t\t\t\t\t<div class=\"p-color-list__img test\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"venobox\" data-gall=\"color\" href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/MJM-FUYUZAKURA-SE19W.png\">\n\t\t\t\t\t\t\t\t\t\t\t<img width=\"1000\" height=\"338\" src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/MJM-FUYUZAKURA-SE19W.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/MJM-FUYUZAKURA-SE19W.png 1000w, https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/MJM-FUYUZAKURA-SE19W-600x203.png 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<p class=\"p-color-list__name\">PSW-MH\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\n\t\n\n\n\n<div class=\"wp-block-group c-row p-spec\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-block-egb-c-grid c-grid\">\n<div class=\"wp-block-egb-c-grid-unit c-grid__u c-grid__u_medium_1of2\">\n\n\t<div class=\"p-gallery\">\n\t\t<div class=\"p-gallery__main\">\n\t\t\t<div class=\"swiper-container\" id=\"js-gallery\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-001.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-001.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-002.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-002.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-003.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-003.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-004.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-004.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-005.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-005.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-006.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-006.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-007.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-007.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-008.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-008.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-009.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-009.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure><a href=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-010.jpg\" class=\"venobox\" ><img src=\"https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-010.jpg\" alt=\"\" width=\"100%\" \/><\/a>\n\t\t\t\t\t\t\t<figcaption><\/figcaption><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<!-- Add Arrows -->\n\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t<\/div>\n\n\t\t\t\t<div class=\"p-gallery__thumbs swiper-container\" id=\"js-thumbs\">\n\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-001.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-002.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-003.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-004.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-005.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-006.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-007.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-008.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-009.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<div class=\"p-gallery__square\" style=\"background-image:url(https:\/\/www.deviser.co.jp\/wp-content\/uploads\/2021\/02\/20191113-MJMFuyuzakura19-010.jpg)\"><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-egb-c-grid-unit c-grid__u c-grid__u_medium_1of2\">\n<h2 class=\"p-spec__title\">Specification<\/h2>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Body Top<\/dt><dd class=\"c-dl__dd\">\n<p>Sakura<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Body<\/dt><dd class=\"c-dl__dd\">\n<p>Ash 2P<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Neck<\/dt><dd class=\"c-dl__dd\">\n<p>Maple<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Fingerboard<\/dt><dd class=\"c-dl__dd\">\n<p>Ebony<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Nut<\/dt><dd class=\"c-dl__dd\">\n<p>Oiled Bone<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Bridge<\/dt><dd class=\"c-dl__dd\">\n<p>Original JM\/JG Type<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Machineheads<\/dt><dd class=\"c-dl__dd\">\n<p>GOTOH\/SD91-05M MG<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Fret<\/dt><dd class=\"c-dl__dd\">\n<p>JESCAR\/Evolution<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Pickups<\/dt><dd class=\"c-dl__dd\">\n<p>Mojotone\/JM&#8217;59CLONE<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Controls<\/dt><dd class=\"c-dl__dd\">\n<p>1Vol,1To,Toggle SW<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Scale<\/dt><dd class=\"c-dl__dd\">\n<p>25.5inch<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Width at Nut<\/dt><dd class=\"c-dl__dd\">\n<p>42.0mm<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Fingerboard Radius<\/dt><dd class=\"c-dl__dd\">\n<p>210R<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Finish<\/dt><dd class=\"c-dl__dd\">\n<p>Top Lacquer<\/p>\n<\/dd><\/dl>\n\n\n\n<dl class=\"wp-block-egb-dl c-dl\"><dt class=\"c-dl__dt\">Accessory<\/dt><dd class=\"c-dl__dd\">\n<p>Hard Case, Allen Wrench, COA<\/p>\n<\/dd><\/dl>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":69807,"menu_order":4584,"template":"","meta":{"spay_email":"","_links_to":"","_links_to_target":""},"brand-cat":[1031,1030],"products-cat":[819],"model-cat":[829],"shape-cat":[923],"price-cat":[831],"products-person-cat":[],"products-year-cat":[955],"products-feature-cat":[966,972],"products-release-cat":[974,1211],"_links":{"self":[{"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products\/69772"}],"collection":[{"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/types\/products"}],"author":[{"embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products\/69772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/media\/69807"}],"wp:attachment":[{"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/media?parent=69772"}],"wp:term":[{"taxonomy":"brand-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/brand-cat?post=69772"},{"taxonomy":"products-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-cat?post=69772"},{"taxonomy":"model-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/model-cat?post=69772"},{"taxonomy":"shape-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/shape-cat?post=69772"},{"taxonomy":"price-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/price-cat?post=69772"},{"taxonomy":"products-person-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-person-cat?post=69772"},{"taxonomy":"products-year-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-year-cat?post=69772"},{"taxonomy":"products-feature-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-feature-cat?post=69772"},{"taxonomy":"products-release-cat","embeddable":true,"href":"https:\/\/www.deviser.co.jp\/en\/wp-json\/wp\/v2\/products-release-cat?post=69772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}